{"id":7284,"date":"2017-10-18T06:28:51","date_gmt":"2017-10-18T11:28:51","guid":{"rendered":"http:\/\/www.pacificadvent.com\/?page_id=7284"},"modified":"2026-04-26T09:56:13","modified_gmt":"2026-04-26T14:56:13","slug":"blog-turismo-veraguas","status":"publish","type":"page","link":"https:\/\/www.pacificadvent.com\/es\/blog-turismo-veraguas\/","title":{"rendered":"Turismo en Veraguas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tan solo 3 millones de a\u00f1os Am\u00e9rica era dos continentes totalmente separados, luego emergi\u00f3 el Istmo de Panam\u00e1, como un puente de interconexi\u00f3n, permitiendo el intercambio biol\u00f3gico m\u00e1s grande de la historia, los animales del norte y del sur se pudieron desplazar libremente entre ambos hemisferios. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como si fuera poco, Panam\u00e1 provoc\u00f3 que cambiara el curso de las corrientes oce\u00e1nicas, lo que caus\u00f3 un colapso en el clima mundial. Y hace poco m\u00e1s de 100 a\u00f1os el ser humano dividi\u00f3 a Panam\u00e1 por la mitad y Am\u00e9rica en dos, nuevamente, al construir el canal de Panam\u00e1, una v\u00eda acu\u00e1tica de tan solo 80 km de longitud, para facilitar el comercio mundial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de esta estrecha franja de tierra se encuentra Veraguas, que a\u00fan conserva esa riqueza natural.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La Historia de Veragua<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Su nombre proviene de la palabra ind\u00edgena &#8220;Verahua&#8221;, &#8220;Veracua&#8221; o &#8220;Viragua&#8221;. Nadie sabe con certeza de d\u00f3nde viene el nombre porque hay m\u00e1s de una historia. Pero me parece muy evidente: \u201cVer-aguas\u201d significa \u201cObservar o Ver &#8211; aguas\u201d en espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de que este territorio fuera conocido como &#8220;Panam\u00e1&#8221;, fue bautizado como &#8220;Veragua&#8221;, una tierra misteriosa al otro lado del mar reclamada por el Reino de Espa\u00f1a.  El nombre de la provincia fue utilizado por primera vez en su forma original en singular, &#8220;Veragua&#8221; por Crist\u00f3bal Col\u00f3n. Fue designado por el Gobernaci\u00f3n de Veragua, el Ducado de Veragua, el Veragua Real y finalmente la provincia de Veraguas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue en la costa norte de Veraguas, donde los espa\u00f1oles se encontraron por primera vez con oro puro; los nativos llevaban grandes platos colgados del cuello como espejos; tambi\u00e9n ten\u00edan adornos de oro de bajo nivel llamado guanin (probablemente una aleaci\u00f3n natural de oro y cobre), de forma tosca, que se asemejaban a las \u00e1guilas, pero que eran m\u00e1s bien del guacamayo o loro sagrado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Col\u00f3n dice en su narraci\u00f3n: &#8220;Es costumbre en este territorio de Veragua enterrar a los jefes con todo el oro que poseen&#8221;;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veragua (antiguo nombre de Veraguas) fue explorado por Crist\u00f3bal Col\u00f3n en su cuarto viaje. Trat\u00f3 de establecer la primera colonia en el nuevo continente espa\u00f1ol, pero fracas\u00f3 debido a los ataques de los indios nativos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Quibi\u00e1n y su pueblo, los habitantes nativos de la zona, masacraron a un grupo de exploraci\u00f3n que hab\u00eda ido r\u00edo arriba. Cuando los cad\u00e1veres espa\u00f1oles llegaron flotando r\u00edo abajo, Col\u00f3n carg\u00f3 los barcos y zarp\u00f3 hacia La Espa\u00f1ola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los conquistadores regresaron a la zona dos d\u00e9cadas despu\u00e9s y finalmente vencieron a Quibi\u00e1n y sus hombres. Panam\u00e1 fue el primer pa\u00eds del continente americano en ser explotado por su oro, de parte de los europeos durante el per\u00edodo colonial espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de encontrar oro, establecieron minas y en 1560 fundaron la ciudad de Concepci\u00f3n (ahora desaparecida), a 10 km al oeste de R\u00edo Bel\u00e9n. Se trajeron esclavos africanos para extraer oro y operar la fundici\u00f3n en Concepci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con las minas completamente agotadas en 1590, muchos mineros huyeron o se dedicaron a la agricultura en todo el Pac\u00edfico de Veraguas y la Pen\u00ednsula de Azuero.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Veraguas tiene lo Mejor de la Tierra y el Mar<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora el oro de Veraguas no es dorado, es verde, ofrecemos un contacto cercano con la naturaleza y actividades de aventura, monta\u00f1as con selva tropical h\u00fameda, buen clima todo el a\u00f1o, m\u00e1s de 410 costas incluyendo playas de arena blanca, unas 50 islas, m\u00e1s de 200 variedades de orqu\u00eddeas y m\u00e1s de 400 especies de aves, adem\u00e1s de mam\u00edferos, reptiles e insertos, algunos de ellos, no descubiertos por el jet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los turistas quedar\u00e1n impresionados con las hermosas playas famosas por sus pr\u00e1cticas de surf, m\u00e1s de 1.700 hect\u00e1reas de arrecifes de coral bien conservados es un para\u00edso para el buceo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los turistas quedar\u00e1n impresionados por las hermosas playas famosas por sus pr\u00e1cticas de surf, lagos y r\u00edos de aguas cristalinas, altas cascadas y bosques tropicales que abrazan los pies de las altas monta\u00f1as. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veraguas es tambi\u00e9n la tierra del pueblo Guaymi, conocido como los feroces guerreros que derrotaron a los espa\u00f1oles varias veces. Aunque ya no son feroces, todav\u00eda prefieren mantenerse alejados del resto del pa\u00eds. Debido a su aislamiento voluntario, sus pr\u00e1cticas tradicionales y su cultura han permanecido sin cambios durante siglos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tan solo 3 millones de a\u00f1os Am\u00e9rica era dos continentes totalmente separados, luego emergi\u00f3 el Istmo de Panam\u00e1, como un puente de interconexi\u00f3n, permitiendo el intercambio biol\u00f3gico m\u00e1s grande de la historia, los animales del norte y del sur se pudieron desplazar libremente entre ambos hemisferios. Como si fuera poco, Panam\u00e1 provoc\u00f3 que cambiara el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6584,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[193],"tags":[574,583,571,562,565,566,570,564,559,575],"class_list":["post-7284","page","type-page","status-publish","has-post-thumbnail","hentry","category-blog-es","tag-avistamiento-de-cetaceos-panama","tag-ecoturismo-en-panama","tag-pesca-deportiva-en-panama","tag-pesca-en-panama","tag-pesca-inshore-panama","tag-pesca-offshore-en-panama","tag-pesca-riverena-panama","tag-senderismo-en-panama","tag-tour-de-playa-esnorquel-panama","tag-turismo-en-panama"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/pages\/7284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/comments?post=7284"}],"version-history":[{"count":0,"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/pages\/7284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/media\/6584"}],"wp:attachment":[{"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/media?parent=7284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/categories?post=7284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/tags?post=7284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}