{"id":588,"count":0,"description":"Ofrecemos tours de pesca a medida en las aguas cristalinas del Golfo de Montijo, Isla C\u00e9baco, Isla Iguana y el Parque Nacional Coiba. Rebosantes de una amplia gama de especies de trofeos, estos son algunos de los mejores destinos de pesca deportiva en Panam\u00e1. Nuestros capitanes son pescadores apasionados con conocimientos y experiencia inigualables, lo que garantiza la aventura de su vida.","link":"https:\/\/www.pacificadvent.com\/es\/tour-category\/panama-pesca-deportiva\/","name":"Pesca Deportiva","slug":"panama-pesca-deportiva","taxonomy":"tour_category","parent":243,"meta":[],"_links":{"self":[{"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/tour_category\/588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/tour_category"}],"about":[{"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/taxonomies\/tour_category"}],"up":[{"embeddable":true,"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/tour_category\/243"}],"wp:post_type":[{"href":"https:\/\/www.pacificadvent.com\/es\/wp-json\/wp\/v2\/tour?tour_category=588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}